{"id":30,"count":1,"description":"","link":"https:\/\/hereislifeug.org\/test\/category\/iydp\/","name":"IYDP","slug":"iydp","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/hereislifeug.org\/test\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hereislifeug.org\/test\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hereislifeug.org\/test\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hereislifeug.org\/test\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}